{"text_format":"1","workbook":"xlsx","n_sheets":4,"sheets":["Instructions","Minimum Pipe Cover & Angle Work","Storm Drain Pipe Schedule","Resources"],"not_rendered":{"charts":0,"images":4,"macros":1,"external_links":0,"defined_names":14,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Instructions","index":0,"n_rows":30,"n_cols":4,"rows_kept":30,"cut":false,"hidden":false,"merged":[[32,0,32,3],[28,0,28,3],[27,0,27,3],[8,0,8,3],[9,0,9,3],[24,0,24,3],[1,0,1,3],[2,0,2,3],[5,0,5,3],[6,0,6,3],[7,0,7,3],[3,0,3,3]]}
[]
["Minimum Cover/Maximum Angle Worksheet"]
["Disclaimer: This program should only be used for quality control of storm water systems for proposed projects. It is the responsibility of the engineer, not DelDOT, to ensure that all connection locations meet the Department's standards. Errors found after plan approval or during construction will be corrected at the applicant's expense."]
["Class IV or V reinforced concrete pipe may be used in accordance with AASHTO design standards where the cover is shallower than the minimum cover for class III. Information in this worksheet is for guidance only."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["(Figure from Design Guidance Memorandum 1-20 Revised Pipe Materials, 4/7/2020)"]
[]
["Legend:"]
["Any items shown in RED TEXT indicate an issue with that item."]
["Any items shown in GREEN TEXT indicate item is correctly input."]
[null,"User Inputs",null,"Output Fields"]

{"sheet":"Minimum Pipe Cover & Angle Work","index":1,"n_rows":98,"n_cols":93,"rows_kept":98,"cut":false,"hidden":false,"merged":[[96,0,97,0],[96,1,97,1],[96,2,97,2],[96,3,97,3],[96,5,97,5],[96,6,97,6],[96,7,97,7],[96,33,97,33],[96,36,97,36],[94,0,95,0],[94,1,95,1],[94,2,95,2],[94,3,95,3],[94,5,95,5],[94,6,95,6],[94,7,95,7],[94,33,95,33],[94,36,95,36],[92,0,93,0],[92,1,93,1],[92,2,93,2],[92,3,93,3],[92,5,93,5],[92,6,93,6],[92,7,93,7],[92,33,93,33],[92,36,93,36],[90,0,91,0],[90,1,91,1],[90,2,91,2],[90,3,91,3],[90,5,91,5],[90,6,91,6],[90,7,91,7],[90,33,91,33],[90,36,91,36],[88,0,89,0],[88,1,89,1],[88,2,89,2],[88,3,89,3],[88,5,89,5],[88,6,89,6],[88,7,89,7],[88,33,89,33],[88,36,89,36],[86,0,87,0],[86,1,87,1],[86,2,87,2],[86,3,87,3],[86,5,87,5],[86,6,87,6],[86,7,87,7],[86,33,87,33],[86,36,87,36],[84,0,85,0],[84,1,85,1],[84,2,85,2],[84,3,85,3],[84,5,85,5],[84,6,85,6],[84,7,85,7],[84,33,85,33],[84,36,85,36],[82,0,83,0],[82,1,83,1],[82,2,83,2],[82,3,83,3],[82,5,83,5],[82,6,83,6],[82,7,83,7],[82,33,83,33],[82,36,83,36],[80,0,81,0],[80,1,81,1],[80,2,81,2],[80,3,81,3],[80,5,81,5],[80,6,81,6],[80,7,81,7],[80,33,81,33],[80,36,81,36],[78,0,79,0],[78,1,79,1],[78,2,79,2],[78,3,79,3],[78,5,79,5],[78,6,79,6],[78,7,79,7],[78,33,79,33],[78,36,79,36],[76,0,77,0],[76,1,77,1],[76,2,77,2],[76,3,77,3],[76,5,77,5],[76,6,77,6],[76,7,77,7],[76,33,77,33],[76,36,77,36],[74,0,75,0],[74,1,75,1],[74,2,75,2],[74,3,75,3],[74,5,75,5],[74,6,75,6],[74,7,75,7],[74,33,75,33],[74,36,75,36],[72,0,73,0],[72,1,73,1],[72,2,73,2],[72,3,73,3],[72,5,73,5],[72,6,73,6],[72,7,73,7],[72,33,73,33],[72,36,73,36],[0,0,2,36],[70,0,71,0],[70,1,71,1],[70,2,71,2],[70,3,71,3],[70,5,71,5],[70,6,71,6],[70,7,71,7],[70,33,71,33],[70,36,71,36],[68,0,69,0],[68,1,69,1],[68,2,69,2],[68,3,69,3],[68,5,69,5],[68,6,69,6],[68,7,69,7],[68,33,69,33],[68,36,69,36],[66,0,67,0],[66,1,67,1],[66,2,67,2],[66,3,67,3],[66,5,67,5],[66,6,67,6],[66,7,67,7],[66,33,67,33],[66,36,67,36],[64,0,65,0],[64,1,65,1],[64,2,65,2],[64,3,65,3],[64,5,65,5],[64,6,65,6],[64,7,65,7],[64,33,65,33],[64,36,65,36],[62,0,63,0],[62,1,63,1],[62,2,63,2],[62,3,63,3],[62,5,63,5],[62,6,63,6],[62,7,63,7],[62,33,63,33],[62,36,63,36],[60,0,61,0],[60,1,61,1],[60,2,61,2],[60,3,61,3],[60,5,61,5],[60,6,61,6],[60,7,61,7],[60,33,61,33],[60,36,61,36],[58,0,59,0],[58,1,59,1],[58,2,59,2],[58,3,59,3],[58,5,59,5],[58,6,59,6],[58,7,59,7],[58,33,59,33],[58,36,59,36],[56,0,57,0],[56,1,57,1],[56,2,57,2],[56,3,57,3],[56,5,57,5],[56,6,57,6],[56,7,57,7],[56,33,57,33],[56,36,57,36],[54,0,55,0],[54,1,55,1],[54,2,55,2],[54,3,55,3],[54,5,55,5],[54,6,55,6],[54,7,55,7],[54,33,55,33],[54,36,55,36],[52,0,53,0],[52,1,53,1],[52,2,53,2],[52,3,53,3],[52,5,53,5],[52,6,53,6],[52,7,53,7],[52,33,53,33],[52,36,53,36],[46,36,47,36],[48,36,49,36],[50,36,51,36],[4,0,4,4],[4,18,4,22],[40,33,41,33],[42,33,43,33],[44,33,45,33],[46,33,47,33],[48,33,49,33],[50,33,51,33],[10,36,11,36],[12,36,13,36],[14,36,15,36],[16,36,17,36],[18,36,19,36],[20,36,21,36],[22,36,23,36],[24,36,25,36],[26,36,27,36],[28,36,29,36],[30,36,31,36],[32,36,33,36],[34,36,35,36],[40,36,41,36],[42,36,43,36],[44,36,45,36],[24,33,25,33],[8,36,9,36],[26,33,27,33],[28,33,29,33],[30,33,31,33],[32,33,33,33],[34,33,35,33],[36,33,37,33],[38,33,39,33],[10,33,11,33],[12,33,13,33],[14,33,15,33],[16,33,17,33],[18,33,19,33],[20,33,21,33],[22,33,23,33],[36,36,37,36],[38,36,39,36],[50,0,51,0],[50,1,51,1],[50,2,51,2],[50,3,51,3],[50,5,51,5],[50,6,51,6],[50,7,51,7],[48,0,49,0],[48,1,49,1],[48,2,49,2],[48,3,49,3],[48,5,49,5],[48,6,49,6],[44,7,45,7],[46,0,47,0],[46,1,47,1],[46,2,47,2],[46,3,47,3],[46,5,47,5],[48,7,49,7],[46,6,47,6],[46,7,47,7],[44,0,45,0],[44,1,45,1],[44,2,45,2],[44,3,45,3],[44,5,45,5],[44,6,45,6],[38,0,39,0],[38,1,39,1],[36,2,37,2],[38,2,39,2],[28,6,29,6],[34,1,35,1],[36,1,37,1],[36,3,37,3],[36,5,37,5],[28,0,29,0],[30,0,31,0],[30,1,31,1],[28,1,29,1],[30,2,31,2],[32,2,33,2],[28,2,29,2],[36,0,37,0],[32,0,33,0],[32,1,33,1],[34,0,35,0],[34,2,35,2],[28,3,29,3],[28,5,29,5],[32,5,33,5],[42,0,43,0],[42,1,43,1],[42,2,43,2],[42,3,43,3],[42,5,43,5],[42,6,43,6],[42,7,43,7],[40,0,41,0],[40,1,41,1],[40,2,41,2],[40,3,41,3],[40,5,41,5],[40,6,41,6],[40,7,41,7],[34,6,35,6],[34,3,35,3],[34,5,35,5],[36,7,37,7],[30,5,31,5],[36,6,37,6],[30,6,31,6],[38,3,39,3],[38,5,39,5],[38,6,39,6],[38,7,39,7],[32,6,33,6],[32,7,33,7],[30,3,31,3],[24,65,24,75],[26,63,37,63],[18,6,19,6],[18,7,19,7],[18,2,19,2],[26,6,27,6],[26,7,27,7],[30,7,31,7],[20,0,21,0],[20,1,21,1],[20,3,21,3],[20,5,21,5],[24,6,25,6],[24,7,25,7],[22,0,23,0],[22,1,23,1],[22,3,23,3],[22,5,23,5],[24,0,25,0],[24,1,25,1],[24,5,25,5],[20,2,21,2],[22,2,23,2],[20,6,21,6],[9,63,15,63],[8,1,9,1],[10,6,11,6],[10,7,11,7],[12,6,13,6],[12,7,13,7],[14,6,15,6],[14,7,15,7],[12,1,13,1],[12,3,13,3],[12,5,13,5],[10,2,11,2],[14,2,15,2],[14,1,15,1],[14,3,15,3],[14,5,15,5],[10,62,35,62],[18,5,19,5],[10,5,11,5],[26,2,27,2],[22,7,23,7],[26,1,27,1],[26,3,27,3],[26,5,27,5],[4,34,4,36],[3,0,3,1],[5,20,7,20],[5,30,7,30],[18,0,19,0],[18,1,19,1],[18,3,19,3],[16,3,17,3],[16,5,17,5],[16,2,17,2],[16,6,17,6],[16,7,17,7],[16,1,17,1],[10,0,11,0],[14,0,15,0],[16,0,17,0],[5,33,7,33],[5,34,7,34],[5,36,7,36],[5,31,7,31],[5,35,7,35],[8,33,9,33],[10,1,11,1],[10,3,11,3],[3,20,3,21],[98,0,99,0],[98,1,99,1],[98,2,99,2],[98,3,99,3],[98,5,99,5],[98,6,99,6],[98,7,99,7],[20,7,21,7],[22,6,23,6],[12,2,13,2],[12,0,13,0],[8,0,9,0],[8,3,9,3],[8,5,9,5],[4,8,4,12],[3,15,3,17],[34,7,35,7],[32,3,33,3],[3,2,3,10],[26,0,27,0],[24,3,25,3],[24,2,25,2],[28,7,29,7],[5,22,7,22],[4,30,4,33],[8,6,9,6],[8,7,9,7],[5,21,7,21],[5,0,7,0],[5,1,7,1],[5,2,7,2],[5,3,7,3],[5,15,7,15],[5,17,7,17],[5,18,7,18],[5,32,7,32],[4,15,4,17],[8,2,9,2],[4,13,4,14],[98,36,99,36],[100,0,101,0],[100,1,101,1],[100,2,101,2],[100,3,101,3],[100,5,101,5],[100,6,101,6],[100,7,101,7],[100,33,101,33],[100,36,101,36],[98,33,99,33],[102,0,103,0],[102,1,103,1],[102,2,103,2],[102,3,103,3],[102,5,103,5],[102,6,103,6],[102,7,103,7],[102,33,103,33],[102,36,103,36],[104,0,105,0],[104,1,105,1],[104,2,105,2],[104,3,105,3],[104,5,105,5],[104,6,105,6],[104,7,105,7],[104,33,105,33],[104,36,105,36],[106,0,107,0],[106,1,107,1],[106,2,107,2],[106,3,107,3],[106,5,107,5],[106,6,107,6],[106,7,107,7],[106,33,107,33],[106,36,107,36],[108,0,109,0],[108,1,109,1],[108,2,109,2],[108,3,109,3],[108,5,109,5],[108,6,109,6],[108,7,109,7],[108,33,109,33],[108,36,109,36],[110,0,111,0],[110,1,111,1],[110,2,111,2],[110,3,111,3],[110,5,111,5],[110,6,111,6],[110,7,111,7],[110,33,111,33],[110,36,111,36],[112,0,113,0],[112,1,113,1],[112,2,113,2],[112,3,113,3],[112,5,113,5],[112,6,113,6],[112,7,113,7],[112,33,113,33],[112,36,113,36],[114,0,115,0],[114,1,115,1],[114,2,115,2],[114,3,115,3],[114,5,115,5],[114,6,115,6],[114,7,115,7],[114,33,115,33],[114,36,115,36],[116,0,117,0],[116,1,117,1],[116,2,117,2],[116,3,117,3],[116,5,117,5],[116,6,117,6],[116,7,117,7],[116,33,117,33],[116,36,117,36],[118,0,119,0],[118,1,119,1],[118,2,119,2],[118,3,119,3],[118,5,119,5],[118,6,119,6],[118,7,119,7],[118,33,119,33],[118,36,119,36],[120,0,121,0],[120,1,121,1],[120,2,121,2],[120,3,121,3],[120,5,121,5],[120,6,121,6],[120,7,121,7],[120,33,121,33],[120,36,121,36],[122,0,123,0],[122,1,123,1],[122,2,123,2],[122,3,123,3],[122,5,123,5],[122,6,123,6],[122,7,123,7],[122,33,123,33],[122,36,123,36],[124,0,125,0],[124,1,125,1],[124,2,125,2],[124,3,125,3],[124,5,125,5],[124,6,125,6],[124,7,125,7],[124,33,125,33],[124,36,125,36],[126,0,127,0],[126,1,127,1],[126,2,127,2],[126,3,127,3],[126,5,127,5],[126,6,127,6],[126,7,127,7],[126,33,127,33],[126,36,127,36],[128,0,129,0],[128,1,129,1],[128,2,129,2],[128,3,129,3],[128,5,129,5],[128,6,129,6],[128,7,129,7],[128,33,129,33],[128,36,129,36],[130,0,131,0],[130,1,131,1],[130,2,131,2],[130,3,131,3],[130,5,131,5],[130,6,131,6],[130,7,131,7],[130,33,131,33],[130,36,131,36]]}
["Minimum Cover / Maximum Angle Worksheet for RCP and HDPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"RCP","III"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ERCP","IV"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"HDPE","V"]
["Project Name:",null,"Project Name",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date:"]
["Pipe Information",null,null,null,null,null,null,null,"Inlet / Structure Information",null,null,null,null,"Top Unit Application",null,"Angles",null,null,"Cover Requirements",null,null,null,null,null,null,null,null,null,null,null,"RCP",null,null,null,"HDPE",null,null,null,null,null,"Pipe Size","Equiv Diameter","Conc Thickness","HDPE Thickness","Actual Size",null,null,null,null,null,null,null,null,null,"RCP Actual Size Chart"]
["Pipe ID","Pipe Material","Pipe Length (Ft.)","Pipe Size (in.)","Pipe Invert Elev.","Equiv. Pipe Diam. (in.)","Actual Size (in.)","Pipe Thickness (in.)","Structure ID","Structure Top Unit Type","T.G. Elevation ","Structure Size ","Str. Wall Width ","Curb Type/ Swale/ Pavement","Curb /Top Unit Compatible","Maximum Angle Allowed ","Actual Angle ","Meets Allowable Angle","Coverage Required For Inlet or MH(in.)","Min. Invert Elevation","Meets Min. Cover for Structure","Pavement Type","Pavement Depth to Top of Base Course (in)","Rigid Cover Complinace RCP","Flexible Cover Compliance RCP","Rigid Cover Compliance HDPE","Flexible Cover Compliance HDPE","Class IV Guidance Only","Class V Guidance Only","Top of Pipe Elevation","Meets Min. Cover for Class III RCP (DGM 1-20)","Calculated Cover (ft)","Class IV or V RCP (For Guidance Only) ","Pipe Class Selected Based on LRFD / ACPA","Meets Min. Cover for Standard HDPE (DGM1-20)","Calculated Cover (ft)","Manufacturer Required HDPE",null,null,"RCP",12,"-",2,null,12,null,"Inlet ","Side 1","Side 2","Coverage Required",null,"Inlet Size Master List",null,"Inlet Top Unit Type","Pipe Size","Equiv Dia","Conc Thickness","Actual Size",null,null,null,null,null,null,null,"RCP Pipe Sizes (with Wall Thickness)",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ERCP Pipe Sizes (with Wall Thickness)"]
[null,null,null,null,"US",null,null,null,"US","US","US","US","US","US","US",null,"US",null,null,"Upstream",null,null,null,"Upstream","Upstream","Upstream","Upstream","Upstream","Upstream","Upstream"]
[null,null,null,null,"DS",null,null,null,"DS","DS","DS","DS","DS","DS","DS",null,"DS",null,null,"Downstream",null,null,null,"Downstream","Downstream","Downstream","Downstream","Downstream","Downstream","Downstream"]
["P-100","RCP",45,15,100,{"$f":"LOOKUP(D9,$AO$6:$AP$32)","v":"-"},{"$f":"IF($B9=\"RCP\",LOOKUP($D9,$AO$6:$AO$33,$AS$6:$AS$33),IF($B9=\"ERCP\",LOOKUP($D9,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D9,$AO$35:$AO$48,$AR$35:$AR$48)))","v":15},{"$f":"IF($B9=\"RCP\",LOOKUP($D9,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B9=\"ERCP\",LOOKUP($D9,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D9,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":2.25},"DI-100","B",110,"34\"x24\"",24,"IPCC 1-4",{"$f":"IF(N9<>\"\", INDEX(BN61:CC68, MATCH(J9,BM$61:BM$68,),MATCH(N9,BN$60:CC$60,)),\" \")","v":"NO"},{"$f":"IF(B9=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M9,$BM$9:$BM$21,),MATCH(D9,$BM$9:$CA$9,)),IF(B9=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M9,$CB$9:$CB$21,),MATCH(D9,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M9,$BM$26:$BM$37,),MATCH(D9,$BM$26:$BY$26,))))","v":4.25},null,{"$f":"IF(P9=\"N/A\",\"NO\",IF(P9>=Q9,\"YES\",\"NO\"))","v":"YES"},{"$f":"INDEX(BD$36:BJ$58,MATCH(L9,BC$36:BC$58,),MATCH(J9,BD$35:BJ$35,))","v":10},{"$f":"K9-((G9+H9+S9)/12)","v":107.73},{"$f":"IF(E9<=T9,\"YES\",\"NO\")","v":"YES"},null,null,{"$f":"IF(AND($V9=\"Rigid\",($K9-(($W9/12)+0.75)>=$AD9)),  \"YES\",\"NO\")","v":"NO"},{"$f":"IF(AND($V9=\"Flexible\",(($K9-1)>=$AD9)),\"YES\",\"NO\")","v":"NO"},{"$f":"IF(AND($V9=\"Rigid\",($K9-2>=$AD9)),  \"YES\",\"NO\")","v":"NO"},{"$f":"IF(AND($V9=\"Flexible\",($K9-(($W9/12)+1)>=$AD9)),  \"YES\",\"NO\")","v":"NO"},{"$f":"IF($K9-(($W9/12)+0.5)>=$AD9,  \"YES\",\"NO\")","v":"YES"},{"$f":"IF($K9-(($W9/12))>=$AD9,  \"YES\",\"NO\")","v":"YES"},{"$f":"E9+((G9+H9)/12)","v":101.44},{"$f":"IF($B9=\"HDPE\",\"\",IF(V9=\"Rigid\",X9,Y9))","v":"NO"},{"$f":"IF(AE9=\"\",\"\",K9-AD9)","v":8.56},{"$f":"IF($B9=\"HDPE\",\"\",IF($AE9=\"YES\",\"\",IF(AB9=\"YES\",\"IV\",IF(AC9=\"YES\",\"V\",\"NO\"))))","v":"IV"},null,{"$f":"IF($B9=\"HDPE\",IF(V9=\"Rigid\",Z9,AA9),\"\")","v":""},{"$f":"IF(AI9=\"\",\"\",K9-AD9)","v":""},null,null,null,null,15,"-",2.25,1.2849999999999999,15,null,0,"-","-",0,null,0,0,"A",12,12,2,{"$f":"BD9+(BE9*2)","v":16},null,"Inlet Size",null,null,null,null,null,0,12,15,18,21,24,27,30,33,36,42,48,54,60,null,"14\"x23\"","19\"x30\"","22\"x34\"","24\"x38\"","27\"x42\"","29\"x45\"","32\"x49\"","34\"x53\"","38\"x60\"","43\"x68\"","48\"x76\"","53\"x83\"","58\"x91\""]
[null,null,null,null,98.5,null,null,null,"DI-101","C",101,"66\"x48\"",48,"PCC 1-2","NO",{"$f":"IF(B9=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M10,$BM$9:$BM$21,),MATCH(D9,$BM$9:$CA$9,)),IF(B9=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M10,$CB$9:$CB$21,),MATCH(D9,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M10,$BM$26:$BM$37,),MATCH(D9,$BM$26:$BY$26,))))","v":56.19},null,"YES",18,{"$f":"K10-((G9+H9+S10)/12)","v":98.06},{"$f":"IF(E10<=T10,\"YES\",\"NO\")","v":"NO"},null,null,{"$f":"IF(AND($V10=\"Rigid\",($K10-(($W10/12)+0.75)>=$AD10)),  \"YES\",\"NO\")","v":"NO"},"NO",{"$f":"IF(AND($V10=\"Rigid\",($K10-2>=$AD10)),  \"YES\",\"NO\")","v":"NO"},{"$f":"IF(AND($V10=\"Flexible\",($K10-(($W10/12)+1)>=$AD10)),  \"YES\",\"NO\")","v":"NO"},{"$f":"IF($K10-(($W10/12)+0.5)>=$AD10,  \"YES\",\"NO\")","v":"YES"},{"$f":"IF($K10-(($W10/12))>=$AD10,  \"YES\",\"NO\")","v":"YES"},{"$f":"E10+((G9+H9)/12)","v":99.94},{"$f":"IF($B9=\"HDPE\",\"\",IF(V10=\"Rigid\",X10,Y10))","v":"NO"},{"$f":"IF(AE10=\"\",\"\",K10-AD10)","v":1.06},"IV",null,{"$f":"IF($B9=\"HDPE\",IF(V10=\"Rigid\",Z10,AA10),\"\")","v":""},"",null,null,null,null,18,"-",2.5,1.6,18,null,"34\"x18\"",34,18,10,null,null,null,"B",15,15,2.25,{"$f":"BD10+(BE10*2)","v":19.5},null,0,null,null,null,"Inlet Wall Size",18,0,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A",18,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,{"$f":"LOOKUP(D11,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B11=\"RCP\",LOOKUP($D11,$AO$6:$AO$33,$AS$6:$AS$33),IF($B11=\"ERCP\",LOOKUP($D11,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D11,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B11=\"RCP\",LOOKUP($D11,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B11=\"ERCP\",LOOKUP($D11,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D11,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B11=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M11,$BM$9:$BM$21,),MATCH(D11,$BM$9:$CA$9,)),IF(B11=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M11,$CB$9:$CB$21,),MATCH(D11,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M11,$BM$26:$BM$37,),MATCH(D11,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K11-((G11+H11+S11)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$f":"IF(AND($V11=\"Rigid\",($K11-(($W11/12)+0.75)>=$AD11)),  \"YES\",\"NO\")","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$f":"IF(AND($V11=\"Rigid\",($K11-2>=$AD11)),  \"YES\",\"NO\")","v":{"$error":"#N/A"}},{"$f":"IF(AND($V11=\"Flexible\",($K11-(($W11/12)+1)>=$AD11)),  \"YES\",\"NO\")","v":{"$error":"#N/A"}},{"$f":"IF($K11-(($W11/12)+0.5)>=$AD11,  \"YES\",\"NO\")","v":{"$error":"#N/A"}},{"$f":"IF($K11-(($W11/12))>=$AD11,  \"YES\",\"NO\")","v":{"$error":"#N/A"}},{"$f":"E11+((G11+H11)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B11=\"HDPE\",\"\",IF(V11=\"Rigid\",X11,Y11))","v":{"$error":"#N/A"}},{"$f":"IF(AE11=\"\",\"\",K11-AD11)","v":{"$error":"#N/A"}},{"$f":"IF($B11=\"HDPE\",\"\",IF($AE11=\"YES\",\"\",IF(AB11=\"YES\",\"IV\",IF(AC11=\"YES\",\"V\",\"NO\"))))","v":{"$error":"#N/A"}},null,{"$f":"IF($B11=\"HDPE\",IF(V11=\"Rigid\",Z11,AA11),\"\")","v":""},"",null,null,null,null,21,"-",2.75,1.75,21,null,"34\"x24\"",34,24,10,null,"34\"x18\"",34,"C",18,18,2.5,23,null,18,null,null,"Max Angle Charts",null,24,0,23.28,4.25,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A",24,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B11=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M12,$BM$9:$BM$21,),MATCH(D11,$BM$9:$CA$9,)),IF(B11=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M12,$CB$9:$CB$21,),MATCH(D11,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M12,$BM$26:$BM$37,),MATCH(D11,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K12-((G11+H11+S12)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E12+((G11+H11)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B11=\"HDPE\",\"\",IF(V12=\"Rigid\",X12,Y12))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B11=\"HDPE\",IF(V12=\"Rigid\",Z12,AA12),\"\")","v":""},"",null,null,null,null,24,"-",3,1.9,24,null,"48\"x30\"",48,30,18,null,"34\"x18\"",18,"D",21,21,2.75,26.5,null,24,null,null,null,null,30,0,40.159999999999997,30.05,17.47,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A",30,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,{"$f":"LOOKUP(D13,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B13=\"RCP\",LOOKUP($D13,$AO$6:$AO$33,$AS$6:$AS$33),IF($B13=\"ERCP\",LOOKUP($D13,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D13,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B13=\"RCP\",LOOKUP($D13,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B13=\"ERCP\",LOOKUP($D13,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D13,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B13=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M13,$BM$9:$BM$21,),MATCH(D13,$BM$9:$CA$9,)),IF(B13=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M13,$CB$9:$CB$21,),MATCH(D13,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M13,$BM$26:$BM$37,),MATCH(D13,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K13-((G13+H13+S13)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B13=\"HDPE\",\"\",IF(V13=\"Rigid\",X13,Y13))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B13=\"HDPE\",IF(V13=\"Rigid\",Z13,AA13),\"\")","v":""},"",null,null,null,null,27,"-",3.25,2.2250000000000001,27,null,"48\"x48\"",48,48,18,null,"34\"x24\"",34,"E",24,24,3,30,null,30,null,null,null,null,34,0,47.16,39.090000000000003,29.95,18.670000000000002,0,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A",34,10.01,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B13=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M14,$BM$9:$BM$21,),MATCH(D13,$BM$9:$CA$9,)),IF(B13=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M14,$CB$9:$CB$21,),MATCH(D13,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M14,$BM$26:$BM$37,),MATCH(D13,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K14-((G13+H13+S14)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E14+((G13+H13)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B13=\"HDPE\",\"\",IF(V14=\"Rigid\",X14,Y14))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B13=\"HDPE\",IF(V14=\"Rigid\",Z14,AA14),\"\")","v":""},"",null,null,null,null,30,"-",3.5,2.5499999999999998,30,null,"66\"x30\"",66,30,18,null,"34\"x24\"",24,"S",27,27,3.25,33.5,null,34,null,null,null,null,36,0,41.53,34.659999999999997,27.06,18.87,8.07,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A",36,12.76,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,{"$f":"LOOKUP(D15,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B15=\"RCP\",LOOKUP($D15,$AO$6:$AO$33,$AS$6:$AS$33),IF($B15=\"ERCP\",LOOKUP($D15,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D15,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B15=\"RCP\",LOOKUP($D15,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B15=\"ERCP\",LOOKUP($D15,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D15,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B15=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M15,$BM$9:$BM$21,),MATCH(D15,$BM$9:$CA$9,)),IF(B15=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M15,$CB$9:$CB$21,),MATCH(D15,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M15,$BM$26:$BM$37,),MATCH(D15,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K15-((G15+H15+S15)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B15=\"HDPE\",\"\",IF(V15=\"Rigid\",X15,Y15))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B15=\"HDPE\",IF(V15=\"Rigid\",Z15,AA15),\"\")","v":""},"",null,null,null,null,33,"-",3.75,2.7,33,null,"66\"x48\"",66,48,18,null,"48\"x30\"",48,"MH",30,30,3.5,37,null,36,null,null,null,null,48,0,61.12,56.19,51.04,45.6,39.74,33.26,25.81,16.45,0,"N/A","N/A","N/A","N/A",48,42.31,26.96,14.83,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B15=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M16,$BM$9:$BM$21,),MATCH(D15,$BM$9:$CA$9,)),IF(B15=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M16,$CB$9:$CB$21,),MATCH(D15,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M16,$BM$26:$BM$37,),MATCH(D15,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K16-((G15+H15+S16)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E16+((G15+H15)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B15=\"HDPE\",\"\",IF(V16=\"Rigid\",X16,Y16))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B15=\"HDPE\",IF(V16=\"Rigid\",Z16,AA16),\"\")","v":""},"",null,null,null,null,36,"-",4,2.85,36,null,"66\"x66\"",66,66,18,null,"48\"x30\"",30,"FES",33,33,3.75,40.5,null,48,null,null,null,null,54,0,58.38,54.22,49.88,45.61,40.81,35.700000000000003,30.55,24.43,17.670000000000002,"N/A","N/A","N/A","N/A",54,42.76,31.31,23.55,14.6,2.46,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,{"$f":"LOOKUP(D17,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B17=\"RCP\",LOOKUP($D17,$AO$6:$AO$33,$AS$6:$AS$33),IF($B17=\"ERCP\",LOOKUP($D17,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D17,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B17=\"RCP\",LOOKUP($D17,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B17=\"ERCP\",LOOKUP($D17,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D17,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B17=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M17,$BM$9:$BM$21,),MATCH(D17,$BM$9:$CA$9,)),IF(B17=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M17,$CB$9:$CB$21,),MATCH(D17,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M17,$BM$26:$BM$37,),MATCH(D17,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K17-((G17+H17+S17)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B17=\"HDPE\",\"\",IF(V17=\"Rigid\",X17,Y17))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B17=\"HDPE\",IF(V17=\"Rigid\",Z17,AA17),\"\")","v":""},"",null,null,null,null,42,"-",4.5,3.15,42,null,"72\"x24\"",72,24,18,null,"48\"x48\"",48,null,36,36,4,44,null,54,null,null,null,null,60,0,61.68,58,54.18,50.46,46.32,42.28,37.71,32.82,27.72,14.97,"N/A","N/A","N/A",60,47.99,38.340000000000003,32.130000000000003,25.14,18.100000000000001,7.36,"N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B17=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M18,$BM$9:$BM$21,),MATCH(D17,$BM$9:$CA$9,)),IF(B17=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M18,$CB$9:$CB$21,),MATCH(D17,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M18,$BM$26:$BM$37,),MATCH(D17,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K18-((G17+H17+S18)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E18+((G17+H17)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B17=\"HDPE\",\"\",IF(V18=\"Rigid\",X18,Y18))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B17=\"HDPE\",IF(V18=\"Rigid\",Z18,AA18),\"\")","v":""},"",null,null,null,null,48,"-",5,3,48,null,"72\"x48\"",72,48,18,null,"66\"x30\"",66,null,42,42,4.5,51,null,60,null,null,null,null,66,0,69.59,66.23,62.8,59.29,55.68,51.94,48.03,43.92,39.53,29.51,15.86,"N/A","N/A",66,57.24,48.6,43.31,37.549999999999997,31.84,24.37,14.56,"N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,{"$f":"LOOKUP(D19,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B19=\"RCP\",LOOKUP($D19,$AO$6:$AO$33,$AS$6:$AS$33),IF($B19=\"ERCP\",LOOKUP($D19,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D19,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B19=\"RCP\",LOOKUP($D19,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B19=\"ERCP\",LOOKUP($D19,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D19,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B19=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M19,$BM$9:$BM$21,),MATCH(D19,$BM$9:$CA$9,)),IF(B19=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M19,$CB$9:$CB$21,),MATCH(D19,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M19,$BM$26:$BM$37,),MATCH(D19,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K19-((G19+H19+S19)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B19=\"HDPE\",\"\",IF(V19=\"Rigid\",X19,Y19))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B19=\"HDPE\",IF(V19=\"Rigid\",Z19,AA19),\"\")","v":""},"",null,null,null,null,54,"-",6.25,null,54,null,"72\"x72\"",72,72,18,null,"66\"x30\"",30,null,48,48,5,58,null,66,null,null,null,null,72,0,71.400000000000006,68.36,65.27,62.12,58.89,55.57,52.14,48.57,44.83,36.619999999999997,26.78,12.75,"N/A",72,60.28,52.63,48.04,43.16,38.479999999999997,32.67,25.98,5.46,"N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B19=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M20,$BM$9:$BM$21,),MATCH(D19,$BM$9:$CA$9,)),IF(B19=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M20,$CB$9:$CB$21,),MATCH(D19,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M20,$BM$26:$BM$37,),MATCH(D19,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K20-((G19+H19+S20)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E20+((G19+H19)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B19=\"HDPE\",\"\",IF(V20=\"Rigid\",X20,Y20))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B19=\"HDPE\",IF(V20=\"Rigid\",Z20,AA20),\"\")","v":""},"",null,null,null,null,60,"-",6.75,3.4,60,null,"84\"x24\"",84,24,"Calcs Req",null,"66\"x48\"",66,null,54,54,6.25,66.5,null,72,null,null,null,null,84,0,70.06,67.52,64.95,62.35,59.7,57.02,54.24,51.42,48.52,42.39,35.659999999999997,27.73,18.59,84,60.84,54.65,51.02,47.24,43.73,39.590000000000003,35.14,30.32,20.12,"N/A","N/A","N/A","N/A"]
[null,null,null,null,null,{"$f":"LOOKUP(D21,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B21=\"RCP\",LOOKUP($D21,$AO$6:$AO$33,$AS$6:$AS$33),IF($B21=\"ERCP\",LOOKUP($D21,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D21,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B21=\"RCP\",LOOKUP($D21,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B21=\"ERCP\",LOOKUP($D21,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D21,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B21=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M21,$BM$9:$BM$21,),MATCH(D21,$BM$9:$CA$9,)),IF(B21=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M21,$CB$9:$CB$21,),MATCH(D21,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M21,$BM$26:$BM$37,),MATCH(D21,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K21-((G21+H21+S21)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B21=\"HDPE\",\"\",IF(V21=\"Rigid\",X21,Y21))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B21=\"HDPE\",IF(V21=\"Rigid\",Z21,AA21),\"\")","v":""},"",null,null,null,"ERCP","14\"x23\"",18,2.75,null,14,null,"84\"x30\"",84,30,"Calcs Req",null,"66\"x48\"",48,null,60,60,6.75,73.5,null,84,null,null,null,null,96,0,72.650000000000006,70.44,68.22,65.98,63.7,61.42,59.06,56.68,54.26,49.22,43.96,38.1,31.67,96,64.67,59.4,56.35,53.2,50.32,46.98,43.47,39.799999999999997,32.65,"N/A","N/A","N/A","N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B21=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M22,$BM$9:$BM$21,),MATCH(D21,$BM$9:$CA$9,)),IF(B21=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M22,$CB$9:$CB$21,),MATCH(D21,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M22,$BM$26:$BM$37,),MATCH(D21,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K22-((G21+H21+S22)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E22+((G21+H21)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B21=\"HDPE\",\"\",IF(V22=\"Rigid\",X22,Y22))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B21=\"HDPE\",IF(V22=\"Rigid\",Z22,AA22),\"\")","v":""},"",null,null,null,null,"19\"x30\"",24,3.25,null,19,null,"84\"x48\"",84,48,"Calcs Req",null,"66\"x66\"",66,null,"14x23",18,2.75,"19.5x28.5",null,96]
[null,null,null,null,null,{"$f":"LOOKUP(D23,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B23=\"RCP\",LOOKUP($D23,$AO$6:$AO$33,$AS$6:$AS$33),IF($B23=\"ERCP\",LOOKUP($D23,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D23,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B23=\"RCP\",LOOKUP($D23,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B23=\"ERCP\",LOOKUP($D23,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D23,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B23=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M23,$BM$9:$BM$21,),MATCH(D23,$BM$9:$CA$9,)),IF(B23=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M23,$CB$9:$CB$21,),MATCH(D23,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M23,$BM$26:$BM$37,),MATCH(D23,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K23-((G23+H23+S23)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B23=\"HDPE\",\"\",IF(V23=\"Rigid\",X23,Y23))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B23=\"HDPE\",IF(V23=\"Rigid\",Z23,AA23),\"\")","v":""},"",null,null,null,null,"22\"x34\"",27,3.5,null,22,null,"84\"x54\"",84,54,"Calcs Req",null,"72\"x24\"",72,null,"19x30",24,3.25,"25.5x36.5"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B23=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M24,$BM$9:$BM$21,),MATCH(D23,$BM$9:$CA$9,)),IF(B23=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M24,$CB$9:$CB$21,),MATCH(D23,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M24,$BM$26:$BM$37,),MATCH(D23,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K24-((G23+H23+S24)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E24+((G23+H23)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B23=\"HDPE\",\"\",IF(V24=\"Rigid\",X24,Y24))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B23=\"HDPE\",IF(V24=\"Rigid\",Z24,AA24),\"\")","v":""},"",null,null,null,null,"24\"x38\"",30,3.75,null,24,null,"84\"x72\"",84,72,"Calcs Req",null,"72\"x24\"",24,null,"22x34",27,3.5,"29x41",null,null,null,null,null,null,null,"HDPE Pipe Sizes (with Wall Thickness)"]
[null,null,null,null,null,{"$f":"LOOKUP(D25,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B25=\"RCP\",LOOKUP($D25,$AO$6:$AO$33,$AS$6:$AS$33),IF($B25=\"ERCP\",LOOKUP($D25,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D25,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B25=\"RCP\",LOOKUP($D25,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B25=\"ERCP\",LOOKUP($D25,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D25,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B25=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M25,$BM$9:$BM$21,),MATCH(D25,$BM$9:$CA$9,)),IF(B25=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M25,$CB$9:$CB$21,),MATCH(D25,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M25,$BM$26:$BM$37,),MATCH(D25,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K25-((G25+H25+S25)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B25=\"HDPE\",\"\",IF(V25=\"Rigid\",X25,Y25))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B25=\"HDPE\",IF(V25=\"Rigid\",Z25,AA25),\"\")","v":""},"",null,null,null,null,"27\"x42\"",33,3.75,null,27,null,"84\"x84\"",84,84,"Calcs Req",null,"72\"x48\"",72,null,"24x38",30,3.75,"31.5x45.5",null,null,null,null,null,null,null,"Pipe Sizes"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B25=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M26,$BM$9:$BM$21,),MATCH(D25,$BM$9:$CA$9,)),IF(B25=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M26,$CB$9:$CB$21,),MATCH(D25,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M26,$BM$26:$BM$37,),MATCH(D25,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K26-((G25+H25+S26)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E26+((G25+H25)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B25=\"HDPE\",\"\",IF(V26=\"Rigid\",X26,Y26))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B25=\"HDPE\",IF(V26=\"Rigid\",Z26,AA26),\"\")","v":""},"",null,null,null,null,"29\"x45\"",36,4.5,null,29,null,"96\"x24\"",96,24,"Calcs Req",null,"72\"x48\"",48,null,"27x42",33,3.75,"34.5x49.5",null,null,null,null,null,null,null,0,15,18,21,24,27,30,33,36,42,48,60]
[null,null,null,null,null,{"$f":"LOOKUP(D27,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B27=\"RCP\",LOOKUP($D27,$AO$6:$AO$33,$AS$6:$AS$33),IF($B27=\"ERCP\",LOOKUP($D27,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D27,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B27=\"RCP\",LOOKUP($D27,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B27=\"ERCP\",LOOKUP($D27,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D27,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B27=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M27,$BM$9:$BM$21,),MATCH(D27,$BM$9:$CA$9,)),IF(B27=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M27,$CB$9:$CB$21,),MATCH(D27,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M27,$BM$26:$BM$37,),MATCH(D27,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K27-((G27+H27+S27)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B27=\"HDPE\",\"\",IF(V27=\"Rigid\",X27,Y27))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B27=\"HDPE\",IF(V27=\"Rigid\",Z27,AA27),\"\")","v":""},"",null,null,null,null,"32\"x49\"",39,4.75,null,32,null,"96\"x30\"",96,30,"Calcs Req",null,"72\"x72\"",72,null,"29x45",36,4.5,"38x45",null,null,null,null,null,"Inlet Wall Size",18,0,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B27=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M28,$BM$9:$BM$21,),MATCH(D27,$BM$9:$CA$9,)),IF(B27=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M28,$CB$9:$CB$21,),MATCH(D27,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M28,$BM$26:$BM$37,),MATCH(D27,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K28-((G27+H27+S28)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E28+((G27+H27)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B27=\"HDPE\",\"\",IF(V28=\"Rigid\",X28,Y28))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B27=\"HDPE\",IF(V28=\"Rigid\",Z28,AA28),\"\")","v":""},"",null,null,null,null,"34\"x53\"",42,5,null,34,null,"96\"x48\"",96,48,"Calcs Req",null,"84\"x24\"",84,null,"32x49",39,4.75,"41.5x58.5",null,null,null,null,null,null,24,0,16.010000000000002,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,{"$f":"LOOKUP(D29,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B29=\"RCP\",LOOKUP($D29,$AO$6:$AO$33,$AS$6:$AS$33),IF($B29=\"ERCP\",LOOKUP($D29,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D29,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B29=\"RCP\",LOOKUP($D29,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B29=\"ERCP\",LOOKUP($D29,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D29,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B29=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M29,$BM$9:$BM$21,),MATCH(D29,$BM$9:$CA$9,)),IF(B29=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M29,$CB$9:$CB$21,),MATCH(D29,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M29,$BM$26:$BM$37,),MATCH(D29,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K29-((G29+H29+S29)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B29=\"HDPE\",\"\",IF(V29=\"Rigid\",X29,Y29))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B29=\"HDPE\",IF(V29=\"Rigid\",Z29,AA29),\"\")","v":""},"",null,null,null,null,"38\"x60\"",48,5.5,null,38,null,"96\"x54\"",96,54,"Calcs Req",null,"84\"x24\"",24,null,"34x53",42,5,"44x63",null,null,null,null,null,null,30,0,35.82,24.4,10.34,"N/A","N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B29=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M30,$BM$9:$BM$21,),MATCH(D29,$BM$9:$CA$9,)),IF(B29=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M30,$CB$9:$CB$21,),MATCH(D29,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M30,$BM$26:$BM$37,),MATCH(D29,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K30-((G29+H29+S30)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E30+((G29+H29)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B29=\"HDPE\",\"\",IF(V30=\"Rigid\",X30,Y30))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B29=\"HDPE\",IF(V30=\"Rigid\",Z30,AA30),\"\")","v":""},"",null,null,null,null,"43\"x68\"",54,6,null,43,null,"96\"x72\"",96,72,"Calcs Req",null,"84\"x30\"",84,null,"38x60",48,5.5,"49x71",null,null,null,null,null,null,34,0,43.64,34.83,25.48,13.37,"N/A","N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,{"$f":"LOOKUP(D31,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B31=\"RCP\",LOOKUP($D31,$AO$6:$AO$33,$AS$6:$AS$33),IF($B31=\"ERCP\",LOOKUP($D31,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D31,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B31=\"RCP\",LOOKUP($D31,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B31=\"ERCP\",LOOKUP($D31,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D31,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B31=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M31,$BM$9:$BM$21,),MATCH(D31,$BM$9:$CA$9,)),IF(B31=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M31,$CB$9:$CB$21,),MATCH(D31,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M31,$BM$26:$BM$37,),MATCH(D31,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K31-((G31+H31+S31)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B31=\"HDPE\",\"\",IF(V31=\"Rigid\",X31,Y31))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B31=\"HDPE\",IF(V31=\"Rigid\",Z31,AA31),\"\")","v":""},"",null,null,null,null,"48\"x76\"",60,6.5,null,48,null,"96\"x96\"",96,96,"Calcs Req",null,"84\"x30\"",30,null,null,null,null,null,null,null,null,null,null,null,36,0,46.72,38.75,30.57,20.75,4.37,"N/A","N/A","N/A","N/A","N/A","N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B31=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M32,$BM$9:$BM$21,),MATCH(D31,$BM$9:$CA$9,)),IF(B31=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M32,$CB$9:$CB$21,),MATCH(D31,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M32,$BM$26:$BM$37,),MATCH(D31,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K32-((G31+H31+S32)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E32+((G31+H31)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B31=\"HDPE\",\"\",IF(V32=\"Rigid\",X32,Y32))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B31=\"HDPE\",IF(V32=\"Rigid\",Z32,AA32),\"\")","v":""},"",null,null,null,null,"53\"x83\"",66,7,null,53,null,null,null,null,null,null,"84\"x48\"",84,null,null,null,null,null,null,null,null,null,null,null,48,0,58.93,53.72,48.75,43.48,37.14,30.01,22.38,12.34,"N/A","N/A","N/A"]
[null,null,null,null,null,{"$f":"LOOKUP(D33,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B33=\"RCP\",LOOKUP($D33,$AO$6:$AO$33,$AS$6:$AS$33),IF($B33=\"ERCP\",LOOKUP($D33,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D33,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B33=\"RCP\",LOOKUP($D33,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B33=\"ERCP\",LOOKUP($D33,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D33,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B33=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M33,$BM$9:$BM$21,),MATCH(D33,$BM$9:$CA$9,)),IF(B33=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M33,$CB$9:$CB$21,),MATCH(D33,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M33,$BM$26:$BM$37,),MATCH(D33,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K33-((G33+H33+S33)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B33=\"HDPE\",\"\",IF(V33=\"Rigid\",X33,Y33))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B33=\"HDPE\",IF(V33=\"Rigid\",Z33,AA33),\"\")","v":""},"",null,null,null,null,"58\"x91\"",72,7.5,null,58,null,null,null,null,null,null,"84\"x48\"",48,null,null,null,null,null,null,null,null,null,null,null,54,0,62.74,58.26,54.05,49.65,44.51,38.97,33.47,27.26,9.6,"N/A","N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B33=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M34,$BM$9:$BM$21,),MATCH(D33,$BM$9:$CA$9,)),IF(B33=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M34,$CB$9:$CB$21,),MATCH(D33,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M34,$BM$26:$BM$37,),MATCH(D33,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K34-((G33+H33+S34)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E34+((G33+H33)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B33=\"HDPE\",\"\",IF(V34=\"Rigid\",X34,Y34))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B33=\"HDPE\",IF(V34=\"Rigid\",Z34,AA34),\"\")","v":""},"",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"",84,null,null,"Inlet Top Cover Chart",null,null,null,null,null,null,null,null,60,0,65.709999999999994,61.77,58.1,54.31,49.94,45.33,40.9,36.119999999999997,24.84,10.39,"N/A"]
[null,null,null,null,null,{"$f":"LOOKUP(D35,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B35=\"RCP\",LOOKUP($D35,$AO$6:$AO$33,$AS$6:$AS$33),IF($B35=\"ERCP\",LOOKUP($D35,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D35,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B35=\"RCP\",LOOKUP($D35,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B35=\"ERCP\",LOOKUP($D35,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D35,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B35=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M35,$BM$9:$BM$21,),MATCH(D35,$BM$9:$CA$9,)),IF(B35=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M35,$CB$9:$CB$21,),MATCH(D35,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M35,$BM$26:$BM$37,),MATCH(D35,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K35-((G35+H35+S35)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B35=\"HDPE\",\"\",IF(V35=\"Rigid\",X35,Y35))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B35=\"HDPE\",IF(V35=\"Rigid\",Z35,AA35),\"\")","v":""},"",null,null,null,"HDPE",12,"-",1,12,null,null,null,null,null,null,null,"84\"x72\"",72,null,null,"A","B","C","D","E",null,"MH",null,null,66,0,68.09,64.569999999999993,61.31,57.97,54.15,50.17,46.41,42.45,33.630000000000003,24.37,"N/A"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B35=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M36,$BM$9:$BM$21,),MATCH(D35,$BM$9:$CA$9,)),IF(B35=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M36,$CB$9:$CB$21,),MATCH(D35,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M36,$BM$26:$BM$37,),MATCH(D35,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K36-((G35+H35+S36)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E36+((G35+H35)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B35=\"HDPE\",\"\",IF(V36=\"Rigid\",X36,Y36))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B35=\"HDPE\",IF(V36=\"Rigid\",Z36,AA36),\"\")","v":""},"",null,null,null,null,15,"-",1.2849999999999999,15,null,null,null,null,null,null,null,"84\"x84\"",84,null,null,null,null,null,null,null,null,null,null,null,72,0,70.040000000000006,66.86,63.92,60.93,57.52,54.01,50.73,47.31,39.92,32.67,6.85]
[null,null,null,null,null,{"$f":"LOOKUP(D37,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B37=\"RCP\",LOOKUP($D37,$AO$6:$AO$33,$AS$6:$AS$33),IF($B37=\"ERCP\",LOOKUP($D37,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D37,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B37=\"RCP\",LOOKUP($D37,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B37=\"ERCP\",LOOKUP($D37,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D37,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B37=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M37,$BM$9:$BM$21,),MATCH(D37,$BM$9:$CA$9,)),IF(B37=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M37,$CB$9:$CB$21,),MATCH(D37,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M37,$BM$26:$BM$37,),MATCH(D37,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K37-((G37+H37+S37)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B37=\"HDPE\",\"\",IF(V37=\"Rigid\",X37,Y37))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B37=\"HDPE\",IF(V37=\"Rigid\",Z37,AA37),\"\")","v":""},"",null,null,null,null,18,"-",1.6,18,null,null,null,null,null,null,null,"96\"x24\"",96,null,"34\"x18\"",10,10,10,10,10,10,"Invalid MH Size",null,null,84,0,73.06,70.39,67.930000000000007,65.44,62.63,59.77,57.11,54.39,48.69,43.4,29.34]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B37=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M38,$BM$9:$BM$21,),MATCH(D37,$BM$9:$CA$9,)),IF(B37=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M38,$CB$9:$CB$21,),MATCH(D37,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M38,$BM$26:$BM$37,),MATCH(D37,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K38-((G37+H37+S38)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E38+((G37+H37)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B37=\"HDPE\",\"\",IF(V38=\"Rigid\",X38,Y38))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B37=\"HDPE\",IF(V38=\"Rigid\",Z38,AA38),\"\")","v":""},"",null,null,null,null,21,"-",1.75,21,null,null,null,null,null,null,null,"96\"x24\"",24,null,"34\"x24\"",10,10,10,10,10,10,"Invalid MH Size",null,null,96,0,75.28,72.97,70.86,68.72,66.319999999999993,63.89,61.65,59.38,54.68,50.42,39.840000000000003]
[null,null,null,null,null,{"$f":"LOOKUP(D39,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B39=\"RCP\",LOOKUP($D39,$AO$6:$AO$33,$AS$6:$AS$33),IF($B39=\"ERCP\",LOOKUP($D39,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D39,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B39=\"RCP\",LOOKUP($D39,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B39=\"ERCP\",LOOKUP($D39,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D39,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B39=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M39,$BM$9:$BM$21,),MATCH(D39,$BM$9:$CA$9,)),IF(B39=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M39,$CB$9:$CB$21,),MATCH(D39,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M39,$BM$26:$BM$37,),MATCH(D39,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K39-((G39+H39+S39)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B39=\"HDPE\",\"\",IF(V39=\"Rigid\",X39,Y39))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B39=\"HDPE\",IF(V39=\"Rigid\",Z39,AA39),\"\")","v":""},"",null,null,null,null,24,"-",1.9,24,null,null,null,null,null,null,null,"96\"x30\"",96,null,"48\"x30\"",18,18,18,18,18,18,20]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B39=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M40,$BM$9:$BM$21,),MATCH(D39,$BM$9:$CA$9,)),IF(B39=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M40,$CB$9:$CB$21,),MATCH(D39,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M40,$BM$26:$BM$37,),MATCH(D39,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K40-((G39+H39+S40)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E40+((G39+H39)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B39=\"HDPE\",\"\",IF(V40=\"Rigid\",X40,Y40))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B39=\"HDPE\",IF(V40=\"Rigid\",Z40,AA40),\"\")","v":""},"",null,null,null,null,27,"-",2.2250000000000001,27,null,null,null,null,null,null,null,"96\"x30\"",30,null,"48\"x48\"",18,18,18,18,18,18,20]
[null,null,null,null,null,{"$f":"LOOKUP(D41,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B41=\"RCP\",LOOKUP($D41,$AO$6:$AO$33,$AS$6:$AS$33),IF($B41=\"ERCP\",LOOKUP($D41,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D41,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B41=\"RCP\",LOOKUP($D41,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B41=\"ERCP\",LOOKUP($D41,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D41,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B41=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M41,$BM$9:$BM$21,),MATCH(D41,$BM$9:$CA$9,)),IF(B41=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M41,$CB$9:$CB$21,),MATCH(D41,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M41,$BM$26:$BM$37,),MATCH(D41,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K41-((G41+H41+S41)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B41=\"HDPE\",\"\",IF(V41=\"Rigid\",X41,Y41))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B41=\"HDPE\",IF(V41=\"Rigid\",Z41,AA41),\"\")","v":""},"",null,null,null,null,30,"-",2.5499999999999998,30,null,null,null,null,null,null,null,"84\"x54\"",84,null,"66\"x30\"",18,18,18,18,18,18,20]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B41=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M42,$BM$9:$BM$21,),MATCH(D41,$BM$9:$CA$9,)),IF(B41=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M42,$CB$9:$CB$21,),MATCH(D41,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M42,$BM$26:$BM$37,),MATCH(D41,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K42-((G41+H41+S42)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E42+((G41+H41)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B41=\"HDPE\",\"\",IF(V42=\"Rigid\",X42,Y42))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B41=\"HDPE\",IF(V42=\"Rigid\",Z42,AA42),\"\")","v":""},"",null,null,null,null,33,"-",2.7,33,null,null,null,null,null,null,null,"84\"x54\"",54,null,"66\"x48\"",18,18,18,18,18,18,20,null,"Manhole Sizes For Pulldowns","FES Size for pulldown"]
[null,null,null,null,null,{"$f":"LOOKUP(D43,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B43=\"RCP\",LOOKUP($D43,$AO$6:$AO$33,$AS$6:$AS$33),IF($B43=\"ERCP\",LOOKUP($D43,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D43,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B43=\"RCP\",LOOKUP($D43,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B43=\"ERCP\",LOOKUP($D43,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D43,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B43=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M43,$BM$9:$BM$21,),MATCH(D43,$BM$9:$CA$9,)),IF(B43=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M43,$CB$9:$CB$21,),MATCH(D43,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M43,$BM$26:$BM$37,),MATCH(D43,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K43-((G43+H43+S43)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B43=\"HDPE\",\"\",IF(V43=\"Rigid\",X43,Y43))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B43=\"HDPE\",IF(V43=\"Rigid\",Z43,AA43),\"\")","v":""},"",null,null,null,null,36,"-",2.85,36,null,null,null,null,null,null,null,"96\"x48\"",96,null,"66\"x66\"",18,18,18,18,18,18,20,null,0,0]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B43=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M44,$BM$9:$BM$21,),MATCH(D43,$BM$9:$CA$9,)),IF(B43=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M44,$CB$9:$CB$21,),MATCH(D43,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M44,$BM$26:$BM$37,),MATCH(D43,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K44-((G43+H43+S44)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E44+((G43+H43)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B43=\"HDPE\",\"\",IF(V44=\"Rigid\",X44,Y44))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B43=\"HDPE\",IF(V44=\"Rigid\",Z44,AA44),\"\")","v":""},"",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"96\"x48\"",48,null,"72\"x24\"",18,18,18,18,18,18,"Invalid MH Size",null,"48\"x30\""]
[null,null,null,null,null,{"$f":"LOOKUP(D45,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B45=\"RCP\",LOOKUP($D45,$AO$6:$AO$33,$AS$6:$AS$33),IF($B45=\"ERCP\",LOOKUP($D45,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D45,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B45=\"RCP\",LOOKUP($D45,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B45=\"ERCP\",LOOKUP($D45,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D45,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B45=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M45,$BM$9:$BM$21,),MATCH(D45,$BM$9:$CA$9,)),IF(B45=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M45,$CB$9:$CB$21,),MATCH(D45,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M45,$BM$26:$BM$37,),MATCH(D45,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K45-((G45+H45+S45)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B45=\"HDPE\",\"\",IF(V45=\"Rigid\",X45,Y45))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B45=\"HDPE\",IF(V45=\"Rigid\",Z45,AA45),\"\")","v":""},"",null,null,null,null,42,"-",3.15,42,null,null,null,null,null,null,null,"96\"x72\"",96,null,"72\"x48\"",18,18,18,18,18,18,"Invalid MH Size",null,"48\"x48\""]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B45=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M46,$BM$9:$BM$21,),MATCH(D45,$BM$9:$CA$9,)),IF(B45=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M46,$CB$9:$CB$21,),MATCH(D45,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M46,$BM$26:$BM$37,),MATCH(D45,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K46-((G45+H45+S46)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E46+((G45+H45)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B45=\"HDPE\",\"\",IF(V46=\"Rigid\",X46,Y46))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B45=\"HDPE\",IF(V46=\"Rigid\",Z46,AA46),\"\")","v":""},"",null,null,null,null,48,"-",3,48,null,null,null,null,null,null,null,"96\"x72\"",72,null,"72\"x72\"",18,18,18,18,18,18,"Invalid MH Size",null,"66\"x30\""]
[null,null,null,null,null,{"$f":"LOOKUP(D47,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B47=\"RCP\",LOOKUP($D47,$AO$6:$AO$33,$AS$6:$AS$33),IF($B47=\"ERCP\",LOOKUP($D47,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D47,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B47=\"RCP\",LOOKUP($D47,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B47=\"ERCP\",LOOKUP($D47,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D47,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B47=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M47,$BM$9:$BM$21,),MATCH(D47,$BM$9:$CA$9,)),IF(B47=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M47,$CB$9:$CB$21,),MATCH(D47,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M47,$BM$26:$BM$37,),MATCH(D47,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K47-((G47+H47+S47)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B47=\"HDPE\",\"\",IF(V47=\"Rigid\",X47,Y47))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B47=\"HDPE\",IF(V47=\"Rigid\",Z47,AA47),\"\")","v":""},"",null,null,null,null,54,"-","N/A","N/A",null,null,null,null,null,null,null,"96\"x54\"",96,null,"84\"x24\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size",null,"66\"x48\""]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B47=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M48,$BM$9:$BM$21,),MATCH(D47,$BM$9:$CA$9,)),IF(B47=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M48,$CB$9:$CB$21,),MATCH(D47,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M48,$BM$26:$BM$37,),MATCH(D47,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K48-((G47+H47+S48)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E48+((G47+H47)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B47=\"HDPE\",\"\",IF(V48=\"Rigid\",X48,Y48))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B47=\"HDPE\",IF(V48=\"Rigid\",Z48,AA48),\"\")","v":""},"",null,null,null,null,60,"-",3.4,60,null,null,null,null,null,null,null,"96\"x54\"",54,null,"84\"x30\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size",null,"66\"x66\""]
[null,null,null,null,null,{"$f":"LOOKUP(D49,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B49=\"RCP\",LOOKUP($D49,$AO$6:$AO$33,$AS$6:$AS$33),IF($B49=\"ERCP\",LOOKUP($D49,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D49,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B49=\"RCP\",LOOKUP($D49,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B49=\"ERCP\",LOOKUP($D49,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D49,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B49=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M49,$BM$9:$BM$21,),MATCH(D49,$BM$9:$CA$9,)),IF(B49=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M49,$CB$9:$CB$21,),MATCH(D49,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M49,$BM$26:$BM$37,),MATCH(D49,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K49-((G49+H49+S49)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"IF($B49=\"HDPE\",\"\",IF(V49=\"Rigid\",X49,Y49))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B49=\"HDPE\",IF(V49=\"Rigid\",Z49,AA49),\"\")","v":""},"",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"96\"x96\"",96,null,"84\"x48\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size",null,"72\"x72\""]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B49=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M50,$BM$9:$BM$21,),MATCH(D49,$BM$9:$CA$9,)),IF(B49=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M50,$CB$9:$CB$21,),MATCH(D49,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M50,$BM$26:$BM$37,),MATCH(D49,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K50-((G49+H49+S50)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E50+((G49+H49)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B49=\"HDPE\",\"\",IF(V50=\"Rigid\",X50,Y50))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B49=\"HDPE\",IF(V50=\"Rigid\",Z50,AA50),\"\")","v":""},"",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"84\"x54\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size",null,"84\"x84\""]
[null,null,null,null,null,{"$f":"LOOKUP(D51,$AO$6:$AP$32)","v":{"$error":"#N/A"}},{"$f":"IF($B51=\"RCP\",LOOKUP($D51,$AO$6:$AO$33,$AS$6:$AS$33),IF($B51=\"ERCP\",LOOKUP($D51,$AO$6:$AO$33,$AS$6:$AS$33),LOOKUP($D51,$AO$35:$AO$48,$AR$35:$AR$48)))","v":{"$error":"#N/A"}},{"$f":"IF($B51=\"RCP\",LOOKUP($D51,$AO$6:$AO$33,$AQ$6:$AQ$33),IF($B51=\"ERCP\",LOOKUP($D51,$AO$6:$AO$33,$AQ$6:$AQ$33),LOOKUP($D51,$AO$35:$AO$48,$AQ$35:$AQ$48)))","v":{"$error":"#N/A"}},null,null,null,null,null,null," ",{"$f":"IF(B51=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M51,$BM$9:$BM$21,),MATCH(D51,$BM$9:$CA$9,)),IF(B51=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M51,$CB$9:$CB$21,),MATCH(D51,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M51,$BM$26:$BM$37,),MATCH(D51,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K51-((G51+H51+S51)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E51+((G51+H51)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B51=\"HDPE\",\"\",IF(V51=\"Rigid\",X51,Y51))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B51=\"HDPE\",IF(V51=\"Rigid\",Z51,AA51),\"\")","v":""},"",null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",{"$f":"IF(B51=\"RCP\",INDEX($BM$9:$CA$21,MATCH(M52,$BM$9:$BM$21,),MATCH(D51,$BM$9:$CA$9,)),IF(B51=\"ERCP\",INDEX($CB$9:$CO$21,MATCH(M52,$CB$9:$CB$21,),MATCH(D51,$CB$9:$CO$9,)),INDEX($BM$26:$BY$38,MATCH(M52,$BM$26:$BM$37,),MATCH(D51,$BM$26:$BY$26,))))","v":{"$error":"#N/A"}},null,{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"K52-((G51+H51+S52)/12)","v":{"$error":"#N/A"}},{"$error":"#N/A"},null,null,{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$error":"#N/A"},{"$f":"E52+((G51+H51)/12)","v":{"$error":"#N/A"}},{"$f":"IF($B51=\"HDPE\",\"\",IF(V52=\"Rigid\",X52,Y52))","v":{"$error":"#N/A"}},{"$error":"#N/A"},{"$error":"#N/A"},null,{"$f":"IF($B51=\"HDPE\",IF(V52=\"Rigid\",Z52,AA52),\"\")","v":""},"",null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req",null,null,"Curb Design Requirements"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req",null,null,null,"IPCC 2","IPCC 1-2","IPCC 1-4","IPCC 1-6","IPCC 1-8","IPCC 3-2","IPCC 3-4","IPCC 3-6","IPCC 3-8","PCC 1-2","PCC 1-4","PCC 1-6","PCC 1-8","PCC 2","Swale","Pvm't"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size",null,null,"A","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","YES","YES"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req",null,null,"B","NO","NO","NO","NO","YES","NO","NO","NO","YES","NO","NO","NO","YES","NO","NO","NO"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size",null,null,"C","NO","YES","YES","YES","NO","YES","YES","YES","NO","YES","YES","YES","NO","NO","NO","NO"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req",null,null,"D","YES","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size",null,null,"E","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","YES","NO","NO"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req",null,null,"S","YES","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size",null,null,"MH","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","YES","YES"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req",null,null,"FES","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","NO","YES","NO"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rigid","Class IV",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x72\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Invalid MH Size"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flexible","Class V",null,null,null,null,null,null,null,null,null,null,null,null,"84\"x84\"","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req","Calcs Req"]

{"sheet":"Storm Drain Pipe Schedule","index":2,"n_rows":25,"n_cols":10,"rows_kept":25,"cut":false,"hidden":false,"merged":[[0,0,0,9],[1,8,1,9],[1,1,1,7],[1,0,2,0]]}
["Storm Drainage Pipe Schedule (DCM Figure 4.3.5-c)"]
["Pipe ","Description",null,null,null,null,null,null,"Invert Elevation"]
[null,"From","To","Size","Type","Length","Class","Slope (%)","In","Out"]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A9","v":"P-100"},{"$f":"'Minimum Pipe Cover & Angle Work'!I9","v":"DI-100"},{"$f":"'Minimum Pipe Cover & Angle Work'!I10","v":"DI-101"},{"$f":"'Minimum Pipe Cover & Angle Work'!D9","v":15},{"$f":"'Minimum Pipe Cover & Angle Work'!B9","v":"RCP"},{"$f":"'Minimum Pipe Cover & Angle Work'!C9","v":45},{"$f":"IF(F4=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH9)","v":0},{"$f":"IF(F4>0,((I4-J4)/F4)*100,0)","v":3.33},{"$f":"'Minimum Pipe Cover & Angle Work'!E9","v":100},{"$f":"'Minimum Pipe Cover & Angle Work'!E10","v":98.5}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A11","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I11","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I12","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D11","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B11","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C11","v":0},{"$f":"IF(F5=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH11)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E11","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E12","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A13","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I13","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I14","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D13","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B13","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C13","v":0},{"$f":"IF(F6=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH13)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E13","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E14","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A15","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I15","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I16","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D15","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B15","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C15","v":0},{"$f":"IF(F7=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH15)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E15","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E16","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A17","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I17","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I18","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D17","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B17","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C17","v":0},{"$f":"IF(F8=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH17)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E17","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E18","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A19","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I19","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I20","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D19","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B19","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C19","v":0},{"$f":"IF(F9=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH19)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E19","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E20","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A21","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I21","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I22","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D21","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B21","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C21","v":0},{"$f":"IF(F10=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH21)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E21","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E22","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A23","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I23","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I24","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D23","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B23","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C23","v":0},{"$f":"IF(F11=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH23)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E23","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E24","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A25","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I25","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I26","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D25","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B25","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C25","v":0},{"$f":"IF(F12=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH25)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E25","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E26","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A27","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I27","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I28","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D27","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B27","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C27","v":0},{"$f":"IF(F13=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH27)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E27","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E28","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A29","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I29","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I30","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D29","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B29","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C29","v":0},{"$f":"IF(F14=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH29)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E29","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E30","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A31","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I31","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I32","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D31","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B31","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C31","v":0},{"$f":"IF(F15=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH31)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E31","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E32","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A33","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I33","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I34","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D33","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B33","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C33","v":0},{"$f":"IF(F16=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH33)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E33","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E34","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A35","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I35","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I36","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D35","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B35","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C35","v":0},{"$f":"IF(F17=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH35)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E35","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E36","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A37","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I37","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I38","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D37","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B37","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C37","v":0},{"$f":"IF(F18=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH37)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E37","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E38","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A39","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I39","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I40","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D39","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B39","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C39","v":0},{"$f":"IF(F19=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH39)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E39","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E40","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A41","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I41","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I42","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D41","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B41","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C41","v":0},{"$f":"IF(F20=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH41)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E41","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E42","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A43","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I43","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I44","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D43","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B43","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C43","v":0},{"$f":"IF(F21=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH43)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E43","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E44","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A45","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I45","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I46","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D45","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B45","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C45","v":0},{"$f":"IF(F22=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH45)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E45","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E46","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A47","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I47","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I48","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D47","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B47","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C47","v":0},{"$f":"IF(F23=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH47)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E47","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E48","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A49","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I49","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I50","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D49","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B49","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C49","v":0},{"$f":"IF(F24=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH49)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E49","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E50","v":0}]
[{"$f":"'Minimum Pipe Cover & Angle Work'!A51","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I51","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!I52","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!D51","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!B51","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!C51","v":0},{"$f":"IF(F25=\"HDPE\",\"\",'Minimum Pipe Cover & Angle Work'!AH51)","v":0},0,{"$f":"'Minimum Pipe Cover & Angle Work'!E51","v":0},{"$f":"'Minimum Pipe Cover & Angle Work'!E52","v":0}]

{"sheet":"Resources","index":3,"n_rows":9,"n_cols":1,"rows_kept":9,"cut":false,"hidden":false,"merged":[[32,0,32,3],[1,0,1,3],[2,0,2,3],[5,0,5,3],[6,0,6,3],[7,0,7,3],[8,0,8,3]]}
[]
["Resources"]
[]
[]
[]
[]
[]
[]
["(Figure from Standard Detail D-5 (2012) -3)"]